{"id":9763,"date":"2024-11-08T05:22:33","date_gmt":"2024-11-08T05:22:33","guid":{"rendered":"https:\/\/www.united.org.au\/new\/?post_type=portfolio&#038;p=9763"},"modified":"2025-03-13T04:48:47","modified_gmt":"2025-03-13T04:48:47","slug":"visitas-de-voluntarios","status":"publish","type":"portfolio","link":"https:\/\/www.united.org.au\/new\/es\/portfolio\/visitas-de-voluntarios\/","title":{"rendered":"Visitas de Voluntarios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9763\" class=\"elementor elementor-9763\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6b2df5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6b2df5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65f8092\" data-id=\"65f8092\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e9daf2 elementor-view-default elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"6e9daf2\" data-element_type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-accordion icon-plus\" id=\"wgl-accordion-6e9daf2\" data-type=\"accordion\"><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-1151\" class=\"wgl-accordion_header\" data-default=\"yes\"><span class=\"wgl-accordion_title\">\u00bfQu\u00e9 es el Programa de Voluntarios Visitantes para el Cuidado de Personas Mayores (ACVVS)?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p>El programa ACVVS empareja a voluntarios con personas mayores de 65 a\u00f1os para ofrecer una oportunidad de conexi\u00f3n social a trav\u00e9s de visitas regulares, tanto en casa como en residencias.<\/p><p>Este es un servicio gratuito para ayudar a los ancianos a mantener la conexi\u00f3n social.<\/p><p>Nuestros voluntarios te visitar\u00e1n regularmente una vez a la semana o cada dos semanas para charlar, tomar t\u00e9, jugar a un juego de mesa, dar un corto paseo o acompa\u00f1arte en tus actividades favoritas.<\/p><p>Las visitas regulares de los voluntarios pueden ayudar a mejorar la calidad de vida y a que las personas mayores se sientan menos aisladas.<\/p><\/div><\/div><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-1152\" class=\"wgl-accordion_header\" data-default=\"\"><span class=\"wgl-accordion_title\">\u00bfC\u00f3mo funciona?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p>UNITED recluta, capacita y apoya a los visitantes voluntarios. Emparejamos voluntarios con personas mayores que reciben cuidados y brindamos apoyo para las relaciones que se forman entre los voluntarios y las personas que visitan. United realiza un proceso de selecci\u00f3n (incluyendo verificaciones policiales) para todos los voluntarios antes de comenzar.<\/p><p>Los voluntarios visitar\u00e1n a las personas al menos 20 veces al a\u00f1o. Estas visitas pueden ser:<\/p><p>- Visitas individuales o grupales a residencias de cuidado de mayores.<br \/>- Visitas individuales a personas en la comunidad que reciben Paquetes de Atenci\u00f3n Domiciliaria.<\/p><\/div><\/div><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-1153\" class=\"wgl-accordion_header\" data-default=\"\"><span class=\"wgl-accordion_title\">\u00bfC\u00f3mo puedo recibir visitas de voluntarios?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p>\u00a1Somos una organizaci\u00f3n comunitaria sin fines de lucro que te pone a ti en primer lugar! Nuestros voluntarios no solo son altamente capacitados y entusiastas, sino que tambi\u00e9n est\u00e1n bien preparados para comprender tus necesidades ling\u00fc\u00edsticas y culturales. Te asignaremos un visitante regular que comparta tus intereses, pasatiempos y antecedentes.<\/p><p>Por favor, contacta a nuestra Coordinadora del Programa ACVVS:<br \/>Tel: +61 (03) 9318 2949 <br \/>M\u00f3vil: 0400 805 803 <br \/>Correo: <a href=\"mailto:volunteers.coordination@united.org.au\">volunteers.coordination@united.org.au<\/a><\/p><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b191ef7\" data-id=\"b191ef7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e81bddb elementor-view-default elementor-widget elementor-widget-wgl-toggle-accordion\" data-id=\"e81bddb\" data-element_type=\"widget\" data-widget_type=\"wgl-toggle-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-accordion icon-plus\" id=\"wgl-accordion-e81bddb\" data-type=\"accordion\"><div class=\"wgl-accordion_panel\"><h4 id=\"wgl-accordion_header-2431\" class=\"wgl-accordion_header\" data-default=\"yes\"><span class=\"wgl-accordion_title\">\u00bfC\u00f3mo puedo inscribirme en el ACVVS como voluntario?<\/span><i class=\"wgl-accordion_icon elementor-icon \"><\/i><\/h4><div class=\"wgl-accordion_content\"><p>Contacta al Coordinador de Voluntarios de United utilizando el formulario a continuaci\u00f3n. UNITED evaluar\u00e1 al voluntario para asegurar una compatibilidad adecuada y luego organizar\u00e1 la primera visita.<\/p><p><br \/><a href=\"https:\/\/forms.monday.com\/forms\/e66bb894b3120c8cc1d35d2257864568?r=use1\" target=\"_blank\" style=\"display: inline-block; padding: 10px 20px; font-size: 16px; color: #fff; background-color: #0073e6; text-decoration: none; border-radius: 5px; text-align: center;\" rel=\"noopener\">Ir al formulario online<\/a><\/p><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a135ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a135ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9ec2bd\" data-id=\"c9ec2bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5db528f elementor-widget elementor-widget-spacer\" data-id=\"5db528f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29ff714 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29ff714\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a725ef1\" data-id=\"a725ef1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9a0e409 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a0e409\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-771b068\" data-id=\"771b068\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a815911 elementor-widget-mobile__width-initial aleft elementor-widget elementor-widget-wgl-counter\" data-id=\"a815911\" data-element_type=\"widget\" data-widget_type=\"wgl-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-counter title-inline\"><div class=\"wgl-counter_wrap \"><div class=\"content-wrap\"><div class=\"wgl-counter_value-wrap\"><div class=\"wgl-counter__placeholder-wrap\"><span class=\"wgl-counter__placeholder\">175<\/span><span class=\"wgl-counter__value\" data-start-value=\"0\" data-end-value=\"175\" data-speed=\"2000\">0<\/span><\/div><\/div><h3 class=\"wgl-counter_title\">Horas <br>de servicio al mes<\/h3><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-70834db\" data-id=\"70834db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f4979b elementor-widget-mobile__width-initial aleft elementor-widget elementor-widget-wgl-counter\" data-id=\"5f4979b\" data-element_type=\"widget\" data-widget_type=\"wgl-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-counter title-inline\"><div class=\"wgl-counter_wrap \"><div class=\"content-wrap\"><div class=\"wgl-counter_value-wrap\"><div class=\"wgl-counter__placeholder-wrap\"><span class=\"wgl-counter__placeholder\">40<\/span><span class=\"wgl-counter__value\" data-start-value=\"0\" data-end-value=\"40\" data-speed=\"2000\">0<\/span><\/div><span class=\"wgl-counter__suffix\">+<\/span><\/div><h3 class=\"wgl-counter_title\">incre\u00edbles <br>voluntarios<\/h3><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e7b40c elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"7e7b40c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-053ac5f\" data-id=\"053ac5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b9d495 elementor-widget elementor-widget-spacer\" data-id=\"2b9d495\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254eb9a acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"254eb9a\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"wgl-double_heading\">                <div class=\"dbl__subtitle\"><span>Las actividades incluyen<\/span>                <\/div><h3 class=\"dbl__title-wrapper\"><span class=\"dbl__title dbl-title_1\">\u00bfQu\u00e9 actividades puedo compartir con un voluntario?<\/span><\/h3>        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a2dd5b elementor-widget elementor-widget-spacer\" data-id=\"4a2dd5b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a6cafb elementor-widget elementor-widget-wgl-carousel\" data-id=\"4a6cafb\" data-element_type=\"widget\" data-widget_type=\"wgl-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-carousel_wrapper\"><div id=bighearts_carousel_6a04b74c70fa5 class=\"wgl-carousel pagination_square_border pag_align_center\"><div class=\"wgl-carousel_slick\" data-slick='{\"slidesToShow\":4,\"slidesToScroll\":1,\"infinite\":true,\"variableWidth\":false,\"autoplay\":true,\"autoplaySpeed\":\"3000\",\"speed\":3000,\"arrows\":true,\"dots\":true,\"adaptiveHeight\":false,\"responsive\":[{\"breakpoint\":0,\"settings\":{\"slidesToShow\":4,\"slidesToScroll\":1}},{\"breakpoint\":0,\"settings\":{\"slidesToShow\":2,\"slidesToScroll\":1}},{\"breakpoint\":0,\"settings\":{\"slidesToShow\":1,\"slidesToScroll\":1}}]}'><div class=\"item\"><style>.elementor-9601 .elementor-element.elementor-element-b6a4beb .elementor-widget-container:before{background-color:#FFFFFF;}.elementor-9601 .elementor-element.elementor-element-b6a4beb .elementor-widget-container:after{background-image:url(\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/10\/blue-blob-e1729808738947.png\");margin:32px -53px -30px -50px;background-position:bottom left;background-repeat:no-repeat;background-size:cover;transition-delay:0.1s;}.elementor-9601 .elementor-element.elementor-element-b6a4beb > .elementor-widget-container{margin:0px 0px 0px 0px;padding:39px 10px 38px 10px;border-radius:10px 10px 10px 10px;}.elementor-9601 .elementor-element.elementor-element-b6a4beb:hover .elementor-widget-container{box-shadow:0px 15px 38px 0px rgba(0, 0, 0, 0.1);}.elementor-9601 .elementor-element.elementor-element-b6a4beb .media-wrapper .elementor-icon{font-size:60px;margin:0px 0px 30px 0px;}.elementor-9601 .elementor-element.elementor-element-b6a4beb.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-343a13a );}.elementor-9601 .elementor-element.elementor-element-b6a4beb.elementor-view-framed .elementor-icon,\n                     .elementor-9601 .elementor-element.elementor-element-b6a4beb.elementor-view-default .elementor-icon{color:var( --e-global-color-343a13a );border-color:var( --e-global-color-343a13a );fill:var( --e-global-color-343a13a );}.elementor-9601 .elementor-element.elementor-element-b6a4beb.elementor-view-framed .elementor-icon svg,\n                     .elementor-9601 .elementor-element.elementor-element-b6a4beb.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-343a13a );border-color:var( --e-global-color-343a13a );}.elementor-9601 .elementor-element.elementor-element-b6a4beb .wgl-infobox_title{margin:0px 0px 12px 0px;color:#232323;}.elementor-9601 .elementor-element.elementor-element-b6a4beb .wgl-infobox_content{font-family:\"Montserrat\", Sans-serif;font-weight:400;}.elementor-9601 .elementor-element.elementor-element-b6a4beb .elementor-widget-container{transition:0.4s;}.elementor-9601 .elementor-element.elementor-element-b6a4beb .elementor-widget-container,\n\t\t\t\t     .elementor-9601 .elementor-element.elementor-element-b6a4beb div.elementor-widget-container:after{transition-delay:0s;}.elementor-9601 .elementor-element.elementor-element-b6a4beb .elementor-widget-container:hover:after{transition-delay:0.1s;}@media(max-width:1200px) and (min-width:768px){.elementor-9601 .elementor-element.elementor-element-db91f91{width:50%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9601\" class=\"elementor elementor-9601\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9815a09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9815a09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-db91f91\" data-id=\"db91f91\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6a4beb acenter elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"b6a4beb\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-top\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon fas fa-walking\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">DISFRUTA DE UN PASE AL AIRE FRESCO<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p>Da un paseo con un voluntario para disfrutar del aire libre y respirar aire fresco. Es una forma sencilla de mantenerse activo y conectar con la naturaleza, adaptada a tu propio ritmo y preferencias.<\/p><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"item\"><style>.elementor-9598 .elementor-element.elementor-element-43c7cb3 .elementor-widget-container:before{background-color:#FFFFFF;}.elementor-9598 .elementor-element.elementor-element-43c7cb3 .elementor-widget-container:after{background-image:url(\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/10\/orange-blob.png\");margin:32px -53px -30px -50px;background-position:bottom left;background-repeat:no-repeat;background-size:cover;transition-delay:0.1s;}.elementor-9598 .elementor-element.elementor-element-43c7cb3 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:39px 10px 38px 10px;border-radius:10px 10px 10px 10px;}.elementor-9598 .elementor-element.elementor-element-43c7cb3:hover .elementor-widget-container{box-shadow:0px 15px 38px 0px rgba(0, 0, 0, 0.1);}.elementor-9598 .elementor-element.elementor-element-43c7cb3 .media-wrapper .elementor-icon{font-size:60px;margin:0px 0px 30px 0px;padding:0px 0px 0px 0px;}.elementor-9598 .elementor-element.elementor-element-43c7cb3.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-75de7af );}.elementor-9598 .elementor-element.elementor-element-43c7cb3.elementor-view-framed .elementor-icon,\n                     .elementor-9598 .elementor-element.elementor-element-43c7cb3.elementor-view-default .elementor-icon{color:var( --e-global-color-75de7af );border-color:var( --e-global-color-75de7af );fill:var( --e-global-color-75de7af );}.elementor-9598 .elementor-element.elementor-element-43c7cb3.elementor-view-framed .elementor-icon svg,\n                     .elementor-9598 .elementor-element.elementor-element-43c7cb3.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-75de7af );border-color:var( --e-global-color-75de7af );}.elementor-9598 .elementor-element.elementor-element-43c7cb3 .wgl-infobox_title{margin:0px 0px 12px 0px;color:#232323;}.elementor-9598 .elementor-element.elementor-element-43c7cb3 .wgl-infobox_content{font-family:\"Montserrat\", Sans-serif;font-weight:400;}.elementor-9598 .elementor-element.elementor-element-43c7cb3 .elementor-widget-container{transition:0.4s;}.elementor-9598 .elementor-element.elementor-element-43c7cb3 .elementor-widget-container,\n\t\t\t\t     .elementor-9598 .elementor-element.elementor-element-43c7cb3 div.elementor-widget-container:after{transition-delay:0s;}.elementor-9598 .elementor-element.elementor-element-43c7cb3 .elementor-widget-container:hover:after{transition-delay:0.1s;}@media(max-width:1200px) and (min-width:768px){.elementor-9598 .elementor-element.elementor-element-ccac3d2{width:50%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9598\" class=\"elementor elementor-9598\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d619a8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d619a8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ccac3d2\" data-id=\"ccac3d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43c7cb3 acenter elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"43c7cb3\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-top\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon fas fa-book-reader\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">COMPARTIR UN LIBRO<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p>Disfruta del placer de leer un libro junto con un voluntario. Es una excelente manera de relajarse, aprender y compartir experiencias a trav\u00e9s de historias, adaptadas a tus gustos literarios.<\/p><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"item\"><style>.elementor-9595 .elementor-element.elementor-element-2071db5 .elementor-widget-container:before{background-color:#FFFFFF;}.elementor-9595 .elementor-element.elementor-element-2071db5 .elementor-widget-container:after{background-image:url(\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/10\/purple-blob.png\");margin:32px -53px -30px -50px;background-position:bottom left;background-repeat:no-repeat;background-size:cover;transition-delay:0.1s;}.elementor-9595 .elementor-element.elementor-element-2071db5 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:39px 10px 38px 10px;border-radius:10px 10px 10px 10px;}.elementor-9595 .elementor-element.elementor-element-2071db5:hover .elementor-widget-container{box-shadow:0px 15px 38px 0px rgba(0, 0, 0, 0.1);}.elementor-9595 .elementor-element.elementor-element-2071db5 .media-wrapper .elementor-icon{font-size:60px;margin:0px 0px 30px 0px;}.elementor-9595 .elementor-element.elementor-element-2071db5.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-7c5bbc3 );}.elementor-9595 .elementor-element.elementor-element-2071db5.elementor-view-framed .elementor-icon,\n                     .elementor-9595 .elementor-element.elementor-element-2071db5.elementor-view-default .elementor-icon{color:var( --e-global-color-7c5bbc3 );border-color:var( --e-global-color-7c5bbc3 );fill:var( --e-global-color-7c5bbc3 );}.elementor-9595 .elementor-element.elementor-element-2071db5.elementor-view-framed .elementor-icon svg,\n                     .elementor-9595 .elementor-element.elementor-element-2071db5.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-7c5bbc3 );border-color:var( --e-global-color-7c5bbc3 );}.elementor-9595 .elementor-element.elementor-element-2071db5 .wgl-infobox_title{margin:0px 0px 12px 0px;color:#232323;}.elementor-9595 .elementor-element.elementor-element-2071db5 .wgl-infobox_content{font-family:\"Montserrat\", Sans-serif;font-weight:400;}.elementor-9595 .elementor-element.elementor-element-2071db5 .elementor-widget-container{transition:0.4s;}.elementor-9595 .elementor-element.elementor-element-2071db5 .elementor-widget-container,\n\t\t\t\t     .elementor-9595 .elementor-element.elementor-element-2071db5 div.elementor-widget-container:after{transition-delay:0s;}.elementor-9595 .elementor-element.elementor-element-2071db5 .elementor-widget-container:hover:after{transition-delay:0.1s;}@media(max-width:1200px) and (min-width:768px){.elementor-9595 .elementor-element.elementor-element-2b0cd24{width:50%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9595\" class=\"elementor elementor-9595\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80baa49 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80baa49\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2b0cd24\" data-id=\"2b0cd24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2071db5 acenter elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"2071db5\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-top\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon flaticon flaticon-chat\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">COMPARTIR EXPERIENCIAS<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p>Conversa con un voluntario y comparte tus experiencias, fomentando conexiones y amistades duraderas. <br \/>Nota: todos los voluntarios hablan espa\u00f1ol<\/p><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"item\"><style>.elementor-9592 .elementor-element.elementor-element-8557737 .elementor-widget-container:before{background-color:#FFFFFF;}.elementor-9592 .elementor-element.elementor-element-8557737 .elementor-widget-container:after{background-image:url(\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/10\/green-blob.png\");margin:32px -53px -30px -50px;background-position:bottom left;background-repeat:no-repeat;background-size:cover;transition-delay:0.1s;}.elementor-9592 .elementor-element.elementor-element-8557737 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:39px 10px 38px 10px;border-radius:10px 10px 10px 10px;}.elementor-9592 .elementor-element.elementor-element-8557737:hover .elementor-widget-container{box-shadow:0px 15px 38px 0px rgba(0, 0, 0, 0.1);}.elementor-9592 .elementor-element.elementor-element-8557737 .media-wrapper .elementor-icon{font-size:60px;margin:0px 0px 30px 0px;}.elementor-9592 .elementor-element.elementor-element-8557737.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-9ddc6e1 );}.elementor-9592 .elementor-element.elementor-element-8557737.elementor-view-framed .elementor-icon,\n                     .elementor-9592 .elementor-element.elementor-element-8557737.elementor-view-default .elementor-icon{color:var( --e-global-color-9ddc6e1 );border-color:var( --e-global-color-9ddc6e1 );fill:var( --e-global-color-9ddc6e1 );}.elementor-9592 .elementor-element.elementor-element-8557737.elementor-view-framed .elementor-icon svg,\n                     .elementor-9592 .elementor-element.elementor-element-8557737.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-9ddc6e1 );border-color:var( --e-global-color-9ddc6e1 );}.elementor-9592 .elementor-element.elementor-element-8557737 .wgl-infobox_title{margin:0px 0px 12px 0px;color:#232323;}.elementor-9592 .elementor-element.elementor-element-8557737 .wgl-infobox_content{font-family:\"Montserrat\", Sans-serif;font-weight:400;}.elementor-9592 .elementor-element.elementor-element-8557737 .elementor-widget-container{transition:0.4s;}.elementor-9592 .elementor-element.elementor-element-8557737 .elementor-widget-container,\n\t\t\t\t     .elementor-9592 .elementor-element.elementor-element-8557737 div.elementor-widget-container:after{transition-delay:0s;}.elementor-9592 .elementor-element.elementor-element-8557737 .elementor-widget-container:hover:after{transition-delay:0.1s;}@media(max-width:1200px) and (min-width:768px){.elementor-9592 .elementor-element.elementor-element-2f0175e{width:50%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9592\" class=\"elementor elementor-9592\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5f2edd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f2edd9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f0175e\" data-id=\"2f0175e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8557737 acenter elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"8557737\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-top\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon fas fa-music\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">ESCUCHAR M\u00daSICA<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p>Disfruten y compartan m\u00fasica juntos. Ya sea escuchando cl\u00e1sicos o explorando nuevas melod\u00edas, esta actividad es perfecta para relajarse y conectar a trav\u00e9s del lenguaje universal de la m\u00fasica.<\/p><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"item\"><style>.elementor-9589 .elementor-element.elementor-element-f647283 .elementor-widget-container:before{background-color:#FFFFFF;}.elementor-9589 .elementor-element.elementor-element-f647283 .elementor-widget-container:after{background-image:url(\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/10\/red-blob.png\");margin:32px -53px -30px -50px;background-position:bottom left;background-repeat:no-repeat;background-size:cover;transition-delay:0.1s;}.elementor-9589 .elementor-element.elementor-element-f647283 > .elementor-widget-container{margin:0px 0px 0px 0px;padding:39px 10px 38px 10px;border-radius:10px 10px 10px 10px;}.elementor-9589 .elementor-element.elementor-element-f647283:hover .elementor-widget-container{box-shadow:0px 15px 38px 0px rgba(0, 0, 0, 0.1);}.elementor-9589 .elementor-element.elementor-element-f647283 .media-wrapper .elementor-icon{font-size:60px;margin:0px 0px 30px 0px;}.elementor-9589 .elementor-element.elementor-element-f647283.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-d6357aa );}.elementor-9589 .elementor-element.elementor-element-f647283.elementor-view-framed .elementor-icon,\n                     .elementor-9589 .elementor-element.elementor-element-f647283.elementor-view-default .elementor-icon{color:var( --e-global-color-d6357aa );border-color:var( --e-global-color-d6357aa );fill:var( --e-global-color-d6357aa );}.elementor-9589 .elementor-element.elementor-element-f647283.elementor-view-framed .elementor-icon svg,\n                     .elementor-9589 .elementor-element.elementor-element-f647283.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-d6357aa );border-color:var( --e-global-color-d6357aa );}.elementor-9589 .elementor-element.elementor-element-f647283 .wgl-infobox_title{margin:0px 0px 12px 0px;color:#232323;}.elementor-9589 .elementor-element.elementor-element-f647283 .wgl-infobox_content{font-family:\"Montserrat\", Sans-serif;font-weight:400;}.elementor-9589 .elementor-element.elementor-element-f647283 .elementor-widget-container{transition:0.4s;}.elementor-9589 .elementor-element.elementor-element-f647283 .elementor-widget-container,\n\t\t\t\t     .elementor-9589 .elementor-element.elementor-element-f647283 div.elementor-widget-container:after{transition-delay:0s;}.elementor-9589 .elementor-element.elementor-element-f647283 .elementor-widget-container:hover:after{transition-delay:0.1s;}@media(max-width:1200px) and (min-width:768px){.elementor-9589 .elementor-element.elementor-element-1f43681{width:50%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9589\" class=\"elementor elementor-9589\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-88c8731 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88c8731\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1f43681\" data-id=\"1f43681\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f647283 acenter elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"f647283\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-top\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon fas fa-film\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">VER PEL\u00cdCULAS<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p>Mira una pel\u00edcula junto con un voluntario. Esta actividad relajante es una excelente manera de disfrutar de un poco de entretenimiento y de conversar sobre los temas y personajes de la pel\u00edcula, todo mientras compartes un tiempo de calidad en buena compa\u00f1\u00eda.<\/p><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"item\"><style>.elementor-9586 .elementor-element.elementor-element-3caf59d .elementor-widget-container:before{background-color:#FFFFFF;}.elementor-9586 .elementor-element.elementor-element-3caf59d .elementor-widget-container:after{background-image:url(\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/10\/blue-blob-e1729808738947.png\");margin:32px -53px -30px -50px;background-position:bottom left;background-repeat:no-repeat;background-size:cover;transition-delay:0.1s;}.elementor-9586 .elementor-element.elementor-element-3caf59d > .elementor-widget-container{margin:0px 0px 0px 0px;padding:39px 10px 38px 10px;border-radius:10px 10px 10px 10px;}.elementor-9586 .elementor-element.elementor-element-3caf59d:hover .elementor-widget-container{box-shadow:0px 15px 38px 0px rgba(0, 0, 0, 0.1);}.elementor-9586 .elementor-element.elementor-element-3caf59d .media-wrapper .elementor-icon{font-size:60px;margin:0px 0px 30px 0px;}.elementor-9586 .elementor-element.elementor-element-3caf59d.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-343a13a );}.elementor-9586 .elementor-element.elementor-element-3caf59d.elementor-view-framed .elementor-icon,\n                     .elementor-9586 .elementor-element.elementor-element-3caf59d.elementor-view-default .elementor-icon{color:var( --e-global-color-343a13a );border-color:var( --e-global-color-343a13a );fill:var( --e-global-color-343a13a );}.elementor-9586 .elementor-element.elementor-element-3caf59d.elementor-view-framed .elementor-icon svg,\n                     .elementor-9586 .elementor-element.elementor-element-3caf59d.elementor-view-default .elementor-icon svg{fill:var( --e-global-color-343a13a );border-color:var( --e-global-color-343a13a );}.elementor-9586 .elementor-element.elementor-element-3caf59d .wgl-infobox_title{margin:0px 0px 12px 0px;color:#232323;}.elementor-9586 .elementor-element.elementor-element-3caf59d .wgl-infobox_content{font-family:\"Montserrat\", Sans-serif;font-weight:400;}.elementor-9586 .elementor-element.elementor-element-3caf59d .elementor-widget-container{transition:0.4s;}.elementor-9586 .elementor-element.elementor-element-3caf59d .elementor-widget-container,\n\t\t\t\t     .elementor-9586 .elementor-element.elementor-element-3caf59d div.elementor-widget-container:after{transition-delay:0s;}.elementor-9586 .elementor-element.elementor-element-3caf59d .elementor-widget-container:hover:after{transition-delay:0.1s;}@media(max-width:1200px) and (min-width:768px){.elementor-9586 .elementor-element.elementor-element-357f708{width:50%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9586\" class=\"elementor elementor-9586\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d08569b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d08569b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-357f708\" data-id=\"357f708\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3caf59d acenter elementor-widget-icon-box wgl-icon-box elementor-view-default elementor-widget elementor-widget-wgl-info-box\" data-id=\"3caf59d\" data-element_type=\"widget\" data-widget_type=\"wgl-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-infobox\"><div class=\"wgl-infobox_wrapper wgl-layout-top\"><div class=\"media-wrapper icon-wrapper\"><span class=\"wgl-icon\" ><i class=\"icon elementor-icon fas fa-coffee\" aria-hidden=\"true\"><\/i><\/span><\/div><div class=\"content_wrapper\"><div class=\"wgl-infobox-title_wrapper\"><h3 class=\"wgl-infobox_title\"><span class=\"wgl-infobox_title-idle\">HORA DE T\u00c9 O CAF\u00c9<\/span><\/h3><\/div><div class=\"wgl-infobox_content\"><p>Disfruta de una taza de t\u00e9 o caf\u00e9 con un voluntario. Esta acogedora actividad es perfecta para conversaciones significativas y para fortalecer la conexi\u00f3n social.<\/p><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-182695e elementor-widget elementor-widget-spacer\" data-id=\"182695e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91b4a20 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"91b4a20\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d6616f\" data-id=\"8d6616f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-133ccd1 elementor-widget elementor-widget-wgl-gallery\" data-id=\"133ccd1\" data-element_type=\"widget\" data-widget_type=\"wgl-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wgl-gallery\"><div data-height=\"200\" data-tablet-height=\"150\" data-mobile-height=\"100\" data-gap=\"21\" data-tablet-gap=\"10\" data-mobile-gap=\"10\" class=\"wgl-gallery_items gallery-justified\"><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"7 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY3NywidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC83LTEuanBnIiwic2xpZGVzaG93IjoiYWxsLTEzM2NjZDEifQ%3D%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/7-1.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/7-1-640x480.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"20230522_111507 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY3OCwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC8yMDIzMDUyMl8xMTE1MDctMS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiYWxsLTEzM2NjZDEifQ%3D%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/20230522_111507-1-scaled.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/20230522_111507-1-scaled-1920x2560.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"image (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY3OSwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9pbWFnZS0xLnBuZyIsInNsaWRlc2hvdyI6ImFsbC0xMzNjY2QxIn0%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/image-1.png\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/image-1-983x738.png\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"image (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4MCwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9pbWFnZS0zLnBuZyIsInNsaWRlc2hvdyI6ImFsbC0xMzNjY2QxIn0%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/image-3.png\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/image-3-1020x757.png\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"IMG_7622\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4MSwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9JTUdfNzYyMi1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiYWxsLTEzM2NjZDEifQ%3D%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG_7622-scaled.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG_7622-scaled-1440x2560.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"IMG-20220413-WA0016\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4MiwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9JTUctMjAyMjA0MTMtV0EwMDE2LmpwZyIsInNsaWRlc2hvdyI6ImFsbC0xMzNjY2QxIn0%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220413-WA0016.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220413-WA0016-2048x1536.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"IMG-20220413-WA0021\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4NCwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9JTUctMjAyMjA0MTMtV0EwMDIxLmpwZyIsInNsaWRlc2hvdyI6ImFsbC0xMzNjY2QxIn0%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220413-WA0021.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220413-WA0021-2048x1536.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"IMG-20220525-WA0010 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4NSwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9JTUctMjAyMjA1MjUtV0EwMDEwLTEuanBnIiwic2xpZGVzaG93IjoiYWxsLTEzM2NjZDEifQ%3D%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220525-WA0010-1.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220525-WA0010-1-2048x1554.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"IMG-20230602-WA0000\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4NiwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9JTUctMjAyMzA2MDItV0EwMDAwLmpwZyIsInNsaWRlc2hvdyI6ImFsbC0xMzNjY2QxIn0%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20230602-WA0000.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20230602-WA0000-959x1024.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"PXL_20230113_065844378\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4NywidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9QWExfMjAyMzAxMTNfMDY1ODQ0Mzc4LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJhbGwtMTMzY2NkMSJ9\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/PXL_20230113_065844378-scaled.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/PXL_20230113_065844378-scaled-2560x1920.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"PXL_20230423_025459526 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4OCwidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9QWExfMjAyMzA0MjNfMDI1NDU5NTI2LTEtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImFsbC0xMzNjY2QxIn0%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/PXL_20230423_025459526-1-scaled.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/PXL_20230423_025459526-1-scaled-1440x2560.jpg\" alt=\"\"><\/a><\/div><div class=\"wgl-gallery_item-wrapper\"><a class=\"wgl-gallery_item\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-133ccd1\" data-elementor-lightbox-title=\"IMG-20220413-WA0020 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODY4MywidXJsIjoiaHR0cHM6XC9cL3d3dy51bml0ZWQub3JnLmF1XC9uZXdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9JTUctMjAyMjA0MTMtV0EwMDIwLTEuanBnIiwic2xpZGVzaG93IjoiYWxsLTEzM2NjZDEifQ%3D%3D\" href=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220413-WA0020-1.jpg\"><img decoding=\"async\" class=\"wgl-gallery_image\" src=\"https:\/\/www.united.org.au\/new\/wp-content\/uploads\/2024\/02\/IMG-20220413-WA0020-1-1536x2048.jpg\" alt=\"\"><\/a><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03df8d7 elementor-widget elementor-widget-spacer\" data-id=\"03df8d7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94fc584 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94fc584\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc178bc\" data-id=\"fc178bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es el Programa de Voluntarios Visitantes para el Cuidado de Personas Mayores (ACVVS)? El programa ACVVS empareja a voluntarios con personas mayores de 65 a\u00f1os para ofrecer una oportunidad de conexi\u00f3n social a trav\u00e9s de visitas regulares, tanto en casa como en residencias. Este es un servicio gratuito para ayudar a los ancianos a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8900,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","portfolio-category":[],"portfolio-tag":[],"class_list":["post-9763","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/portfolio\/9763"}],"collection":[{"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/comments?post=9763"}],"version-history":[{"count":16,"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/portfolio\/9763\/revisions"}],"predecessor-version":[{"id":9975,"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/portfolio\/9763\/revisions\/9975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/media\/8900"}],"wp:attachment":[{"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/media?parent=9763"}],"wp:term":[{"taxonomy":"portfolio-category","embeddable":true,"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/portfolio-category?post=9763"},{"taxonomy":"portfolio-tag","embeddable":true,"href":"https:\/\/www.united.org.au\/new\/wp-json\/wp\/v2\/portfolio-tag?post=9763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}